{"id":1603,"date":"2023-04-19T12:00:04","date_gmt":"2023-04-19T10:00:04","guid":{"rendered":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/?page_id=1603"},"modified":"2023-07-20T18:50:27","modified_gmt":"2023-07-20T16:50:27","slug":"datenschutz","status":"publish","type":"page","link":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/datenschutz\/","title":{"rendered":"Datenschutz"},"content":{"rendered":"<div  class=\"gs_7YW11V row_wrap\">\n<div class=\"wp-block-columns row_xxl is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" id=\"Text\">\n<div class=\"wp-block-column col-12 col-sm-auto is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%;width:100%\">\n<h1 class=\"has-h-1-font-size wp-block-heading\" style=\"font-style:normal;font-weight:700\">Datenschutzerkl\u00e4rung<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Der Schutz personenbezogenen Daten sowie der Privatsph\u00e4re von Besuchern der Website&nbsp;<a href=\"http:\/\/www.mrssporty.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.mrssporty.de<\/a>&nbsp;ist ein besonderes Anliegen der Mrs.Sporty GmbH, Helmholtzstra\u00dfe 2-9, 10587 Berlin. Aus diesem Grund setzen wir uns nach bestem Wissen und Gewissen f\u00fcr den Schutz Ihrer Privatsph\u00e4re und Ihr Recht auf Datenschutz ein, indem wir die ma\u00dfgeblichen datenschutzrechtlichen Vorschriften beachten. Die Erhebung, Speicherung und Verarbeitung personenbezogener Daten \u00fcber die Internetseite&nbsp;<a href=\"http:\/\/www.mrssporty.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.mrssporty.de<\/a>&nbsp;erfolgt nach Ma\u00dfgabe der nachfolgenden Datenschutzerkl\u00e4rung und unter Beachtung des Grundsatzes der Datensparsamkeit und der zweckgebundenen Datenverwendung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">1.&nbsp;&nbsp; &nbsp;Name und Kontakt des f\u00fcr die Verarbeitung Verantwortlichen sowie des Betrieblichen Datenschutzbeauftragten<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Datenschutz-Information gilt f\u00fcr die Datenverarbeitung durch:<br><strong><br>Verantwortlicher f\u00fcr die Datenverarbeitung<\/strong><br>Mrs.Sporty GmbH<br>Helmholtzstr. 2\u20139<br>10587 Berlin<br>Tel.: +49 (0)30 308 305 5<br>Fax: +49 (0)30 308 305 4<br>Mail:&nbsp;<a href=\"javascript:linkTo_UnCryptMailto('jxfiql7fkclXjoppmloqv+ab');\">info(at)mrssporty.de<\/a><br><br><strong>Der externe Datenschutzbeauftragte der Mrs.Sporty GmbH ist wie folgt zu erreichen:<\/strong><br>MediaXS Gesellschaft f\u00fcr Medienrechte mbH<br>Frau Snouber<br>Hohenstaufenring 55<br>50674 K\u00f6ln<br>Tel. Nr.: + 49 (0)221 474 94 86<br><a href=\"mailto:datenschutzbeauftragte@datex.de\">datenschutzbeauftragte@datex.de<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">2.&nbsp;&nbsp; Erhebung und Speicherung Personenbezogener Daten sowie Art und Zweck von deren Verwendung<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>a)&nbsp;&nbsp; &nbsp;Beim Besuch der Website<br><\/strong><br>Beim Aufrufen unserer Website&nbsp;<a href=\"http:\/\/www.mrssporty.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.mrssporty.de<\/a>&nbsp;werden durch den auf Ihrem Endger\u00e4t zum Einsatz kommenden Browser automatisch Informationen an den Server unserer Website gesendet. Diese Informationen werden tempor\u00e4r in einem sog. Logfile gespeichert. Folgende Informationen werden dabei ohne Ihr Zutun erfasst und bis zur automatisierten L\u00f6schung gespeichert:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>IP-Adresse des anfragenden Rechners,<\/li>\n\n\n\n<li>Datum und Uhrzeit des Zugriffs,<\/li>\n\n\n\n<li>Name und URL der abgerufenen Datei,<\/li>\n\n\n\n<li>Website, von der aus der Zugriff erfolgt (Referrer-URL),<\/li>\n\n\n\n<li>verwendeter Browser und ggf. das Betriebssystem Ihres Rechners sowie der Name Ihres Access-Providers.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>Die genannten Daten werden durch uns zu folgenden Zwecken verarbeitet:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Gew\u00e4hrleistung eines reibungslosen Verbindungsaufbaus der Website,<\/li>\n\n\n\n<li>Gew\u00e4hrleistung einer komfortablen Nutzung unserer Website,<\/li>\n\n\n\n<li>Auswertung der Systemsicherheit und -stabilit\u00e4t sowie<\/li>\n\n\n\n<li>zu weiteren administrativen Zwecken.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Die Rechtsgrundlage f\u00fcr die Datenverarbeitung ist Art. 6 Abs. 1 S. 1 lit. f der Datenschutzgrundverordnung (DSGVO). Unser berechtigtes Interesse folgt aus den oben aufgelisteten Zwecken zur Datenverarbeitung. In keinem Fall verwenden wir die erhobenen Daten zu dem Zweck, R\u00fcckschl\u00fcsse auf Ihre Person zu ziehen.<br>Dar\u00fcber hinaus setzen wir beim Besuch unserer Website Cookies sowie Analysedienste ein. N\u00e4here Erl\u00e4uterungen dazu erhalten Sie unter den Ziff. 4 und 5 dieser Datenschutzerkl\u00e4rung.<br><strong><br>b)&nbsp;&nbsp; &nbsp;Bei Anmeldung f\u00fcr unseren Newsletter<\/strong><br>Sofern Sie nach Art. 6 Abs. 1 S. 1 a DSGVO ausdr\u00fccklich eingewilligt haben, verwenden wir Ihre E-Mail-Adresse sowie Ihren Namen und Vornamen sowie Ihr Geburtsdatum und Ihren Mitgliedschaftsstatus bei Mrs.Sporty daf\u00fcr, Ihnen regelm\u00e4\u00dfig unseren Newsletter zu \u00fcbersenden. F\u00fcr den Empfang des Newsletters ist die Angabe der E-Mail-Adresse sowie des Namens und Vornamens erforderlich. Der Newsletter unseres Unternehmens kann von Ihnen nur dann empfangen werden wenn Sie \u00fcber eine g\u00fcltige E-Mail-Adresse verf\u00fcgen und sich f\u00fcr den Newsletterversand registriert haben. An die von Ihnen f\u00fcr den Newsletterversand eingetragene E-Mail-Adresse wird eine Best\u00e4tigungs-E-Mail im Double-Opt-in-Verfahren versendet. Diese Best\u00e4tigungs-E-Mail dient der \u00dcberpr\u00fcfung, ob der Inhaber der E-Mail-Adresse den Empfang des Newsletters autorisiert hat. Die Angabe von Vornamen und Namen ist erforderlich, damit wir Sie im Newsletter namentlich ansprechen k\u00f6nnen. Die Angabe des Geburtsdatums sowie die Angabe, ob Sie Mitglied in einem Mrs.Sporty Club sind, ist optional. Sie dient dazu, Ihnen einen speziellen f\u00fcr Ihre Zielgruppe zugeschnittenen Newsletter zusenden zu k\u00f6nnen. Rechtsgrundlage f\u00fcr die Datenverarbeitung ist ferner Art. 6 Abs. 1 S. 1 lit f. DSGVO. Das berechtigte Interesse folgt aus unserem Interesse an Direktwerbung.<br>Die im Rahmen einer Anmeldung zum Newsletter erhobenen personenbezogenen Daten werden zum Versand unseres Newsletters verwendet. Ferner k\u00f6nnen Abonnenten des Newsletters per E-Mail informiert werden, sofern dies f\u00fcr den Betrieb des Newsletter-Dienstes oder eine diesbez\u00fcgliche Registrierung erforderlich ist, wie dies im Falle von \u00c4nderungen am Newsletterangebot oder bei der Ver\u00e4nderung der technischen Gegebenheiten der Fall sein k\u00f6nnte.<br>Die erhobenen Daten werden in anonymisierter Form auch zu statistischen Zwecken verwendet. Rechtsgrundlage f\u00fcr diese Verarbeitung ist Art. 6 Abs. 1 S. 1 lit f DSGVO. Aus der Auswertung der Statistiken zur Optimierung unseres Angebots folgt das berechtigte Interesse.<br>Die im Rahmen einer Anmeldung zum Newsletter erhobenen Daten werden dar\u00fcber hinaus an den im Rahmen der Einwilligungserkl\u00e4rung zum Newsletterbezug von Ihnen ausgew\u00e4hlten lokalen Franchisepartner zum Zweck des Versand eines Newsletters durch diesen Franchisepartner an Sie \u00fcbermittelt.<br>Rechtsgrundlage f\u00fcr die Weitergabe ist Ihre Einwilligung gem. Art. 6 Abs. 1 S. 1 lit a DSGVO.<br>Bei der Anmeldung zum Newsletter werden ferner folgende Daten gespeichert:<br><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Datum\/Uhrzeit, URL und IP (sofern nicht abgeschaltet) der Registrierung<\/li>\n\n\n\n<li>Datum\/Uhrzeit und IP (sofern nicht abgeschaltet) der Best\u00e4tigung<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Die Erhebung dieser Daten ist erforderlich, um den (m\u00f6glichen Missbrauch) der E-Mail-Adresse einer betroffenen Person zu einem sp\u00e4teren Zeitpunkt nachvollziehen zu k\u00f6nnen und dient deshalb der rechtlichen Absicherung des f\u00fcr die Verarbeitung Verantwortlichen. Rechtsgrundlage f\u00fcr die Verarbeitung ist Art. 6 Abs. 1 S. 1 lit f. DSGVO. Das berechtigte Interesse folgt aus den zuvor beschriebenen Zwecken.<br>Das Abonnement unseres Newsletters k\u00f6nnen Sie jederzeit k\u00fcndigen.<br>Ihre Einwilligung in die Speicherung personenbezogener Daten k\u00f6nnen Sie jederzeit widerrufen.<br>Zum Zwecke der Abmeldung bzw. des Widerrufs der Einwilligung findet sich in jedem Newsletter ein entsprechender Link. Ferner besteht die M\u00f6glichkeit, dies dem f\u00fcr die Verarbeitung Verantwortlichen auf andere Weise, beispielsweise per E-Mail an die Adresse&nbsp;<a href=\"javascript:linkTo_UnCryptMailto('jxfiql7pmloqvkbtpXjoppmloqv+zlj');\">sportynews(at)mrssporty.com<\/a>&nbsp;oder telefonisch unter 030\/ 308 305 5 mitzuteilen.<br>Im Rahmen der Abmeldung vom Newsletter werden optional Daten zu den Gr\u00fcnden f\u00fcr die Abmeldung vom Newsletter erhoben. Die Beantwortung der entsprechenden Fragen ist freiwillig. Die Daten werden anonymisiert gespeichert. Die Datenverarbeitung im Rahmen der Abmeldung beruht auf Grundlage von Art. 6 Abs. 1 S. 1 a DSGVO.<br>Die im Rahmen einer Anmeldung zum Newsletter erhobenen personenbezogenen Daten werden innerhalb eines Monats nach Abmeldung von dem Newsletter gel\u00f6scht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>c)&nbsp;&nbsp; &nbsp;Bei Nutzung unserer Kontaktformulare f\u00fcr ein Probetraining<\/strong><br>Bei Interesse an einem Probetraining bei einem unserer lokalen Franchisepartner bieten wir Ihnen die M\u00f6glichkeit, \u00fcber auf der Website bereitgestellte Formulare Kontakt aufzunehmen. Je nach Formular sind dabei unterschiedliche Angaben notwendig. In unserem 1-Schritt-Formular ist die Angabe Ihres Namens, einer Telefonnummer, der E-Mail-Adresse, des Wunschtermins und die Auswahl des Studios, in dem das Probetraining stattfinden soll, erforderlich. Bei unserem 3-Schritt-Formular ist daneben auch die Anzahl der Personen, die am Probetraining teilnehmen, eine Angabe zu den Zielen des Trainings sowie die Angabe, ob Interesse an unserem Ern\u00e4hrungskonzept besteht, erforderlich. Die Angabe der Kontaktdaten, des Wunschtermins und des Studios ist erforderlich, damit wir bzw. der lokale Franchisepartner Kontakt zu Ihnen aufnehmen und einen Termin f\u00fcr ein Probetraining abstimmen k\u00f6nnen. Die Angabe zu den Zielen des Trainings und dazu, ob Interesse an unserem Ern\u00e4hrungskonzept besteht, erfolgt, damit der lokale Franchisepartner das Probetraining optimal vorbereiten kann. Weitere Angaben k\u00f6nnen freiwillig get\u00e4tigt werden.<br>Die Datenverarbeitung zum Zwecke der Kontaktaufnahme mit uns erfolgt nach Art. 6 Abs. 1 S. 1 lit. a DSGVO auf Grundlage Ihrer freiwillig erteilten Einwilligung. Rechtsgrundlage ist dar\u00fcber hinaus Art. 6 Abs, 1 S. 1 lit b DSGVO und Art. 6 Abs. 1 lit f DSGVO. Das berechtigte Interesse ergibt sich aus dem Interesse des Franchise-Partners Kunden im Zusammenhang mit einem Probetraining zu werben.<br>Die erhobenen Daten werden in anonymisierter Form auch zu statistischen Zwecken verwendet. Rechtsgrundlage f\u00fcr diese Verarbeitung ist Art. 6 Abs. 1 S. 1 lit f DSGVO. Aus der Auswertung der Statistiken zur Optimierung unseres Angebots folgt das berechtigte Interesse.<br>Wir leiten diese Daten an den von Ihnen im Kontaktaufnahmeformular ausgew\u00e4hlten lokalen Franchisepartner weiter, damit dieser mit Ihnen Kontakt wegen eines Probetrainings aufnehmen und das Probetraining vorbereiten kann.<br>Rechtsgrundlage f\u00fcr die Weitergabe sind Art. 6 Abs. 1 S. 1 lit a DSGVO sowie Art. 6 Abs. 1 S. 1 lit b DSGVO,<br>Die f\u00fcr das Probetraining von uns erhobenen personenbezogenen Daten werden nach 6 Monaten gel\u00f6scht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>d)&nbsp;&nbsp; &nbsp;Bei verbindlicher Bestellung einer Mitgliedschaft \u00fcber unsere Mrs.Sporty Clubwebseiten<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Mrs.Sporty GmbH stellt Mrs.Sporty Clubs einzelne Clubwebseiten zur Verf\u00fcgung, die individuelle Informationen und Angebote des jeweiligen Clubs enthalten. Der Name und Inhaber des jeweiligen Mrs.Sporty Club ist durch Angabe des Namens und Kontaktinformationen klar erkenntlich.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Interessenten haben die M\u00f6glichkeit \u00fcber diese Clubwebseite eine verbindliche Bestellung einer Mitgliedschaft an den jeweiligen Mrs.Sporty Club zu adressieren. Alle in der Eingabemaske eingegebenen Daten (u.a. Name, Adresse, E-Mail-Adresse; Kontoinformation) werden direkt an den jeweiligen Mrs.Sporty Club weitergeleitet und unmittelbar nach \u00dcbermittlung bei der Mrs.Sporty GmbH gel\u00f6scht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rechtsgrundlage f\u00fcr die Weitergabe ist Art. 6 Abs. 1 S. 1 lit b, f&nbsp; DSGVO.<br>W\u00e4hrend des Bestellprozess hat die Interessentin ebenfalls die M\u00f6glichkeit ein Konto auf der Online-Trainingsplattform&nbsp;<a href=\"javascript:linkTo_UnCryptMailto('jxfiql7Jop+PmloqvXeljb');\">Mrs.Sporty at home<\/a>&nbsp;anzulegen.&nbsp;<a href=\"javascript:linkTo_UnCryptMailto('jxfiql7Jop+PmloqvXeljb');\">Mrs.Sporty at home<\/a>&nbsp;ist ein Angebot der Sporty Gateway GmbH. Verarbeitet werden die Anmeldedaten (Name, Passwort, E-Mail-Adresse) zum Zwecke der \u00dcbermittlung und Anlage eines&nbsp;<a href=\"javascript:linkTo_UnCryptMailto('jxfiql7Jop+PmloqvXeljb');\">Mrs.Sporty at home<\/a>&nbsp;Kontos bei der Sporty Gateway GmbH. Alle Anmeldedaten werden unmittelbar nach \u00dcbermittlung bei der Mrs.Sporty GmbH gel\u00f6scht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rechtsgrundlage f\u00fcr die \u00dcbermittlung ist Art. 6 Abs. 1 S. 1 lit b, f&nbsp; DSGVO im Rahmen des Nutzungsverh\u00e4ltnisses sowie im \u00dcbrigen Art. 6 Abs. 1 S. 1 lit. a DSGVO.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>e)&nbsp;&nbsp; &nbsp;Bei Nutzung unseres Kontaktformulars zur Anforderung weiterer Informationen<\/strong><br>Bei Interesse an der Anforderung weiterer Informationen zu dem Fitness-Angebot der lokalen Franchisepartner bieten wir Ihnen die M\u00f6glichkeit, \u00fcber ein auf der Website bereitgestelltes Formular Kontakt aufzunehmen. Dabei ist die Angabe Ihres Namens, einer Telefonnummer, der E-Mail-Adresse und die Auswahl des Studios, an dem Sie Interesse haben notwendig, damit wir bzw. der lokale Franchisepartner Kontakt zu Ihnen aufnehmen und Ihnen weitere Informationen zur Verf\u00fcgung stellen k\u00f6nnen.<br>Die Datenverarbeitung zum Zwecke der Kontaktaufnahme mit uns erfolgt nach Art. 6 Abs. 1 S. 1 lit. a DSGVO auf Grundlage Ihrer freiwillig erteilten Einwilligung. Rechtsgrundlage ist dar\u00fcber hinaus Art. 6 Abs, 1 S. 1 lit b DSGVO und Art. 6 Abs. 1 lit f DSGVO. Das berechtigte Interesse ergibt sich aus dem Interesse des Franchise-Partners Kunden im Zusammenhang mit einem Probetraining zu werben.<br>Die erhobenen Daten werden in anonymisierter Form auch zu statistischen Zwecken verwendet. Rechtsgrundlage f\u00fcr diese Verarbeitung ist Art. 6 Abs. 1 S. 1 lit f DSGVO. Aus der Auswertung der Statistiken zur Optimierung unseres Angebots folgt das berechtigte Interesse.<br>Wir leiten diese Daten an den von Ihnen im Kontaktaufnahmeformular ausgew\u00e4hlten lokalen Franchisepartner weiter, damit dieser mit Ihnen Kontakt wegen eines Probetrainings aufnehmen und das Probetraining vorbereiten kann.<br>Die Weitergabe erfolgt nach Art. 6 Abs. 1 S. 1 lit. a DSGVO auf Grundlage Ihrer freiwillig erteilten Einwilligung. Rechtsgrundlage ist dar\u00fcber hinaus Art. 6 Abs, 1 S. 1 lit b DSGVO und Art. 6 Abs. 1 lit f DSGVO. Das berechtigte Interesse ergibt sich aus dem Interesse des Franchise-Partners Kunden im Zusammenhang mit einem Probetraining zu werben.<br>Die von uns erhobenen personenbezogenen Daten werden nach 6 Monaten gel\u00f6scht.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>f)&nbsp;&nbsp; &nbsp;Datenschutz Franchise-Interessenten<\/strong><br>Bei Interesse Franchise-Partner im Rahmen des Mrs.Sporty-Franchisesystem zu werden, bieten wir Ihnen die M\u00f6glichkeit an, \u00fcber Telefon oder E-Mail Kontakt zu uns aufzunehmen. Wir erheben und verarbeiten die personenbezogenen Daten, wie Name, Vorname, Adresse, Telefonnummer, E-Mail-Adresse, Geburtsdatum, von Personen, die sich als Franchise-Partner bewerben, zum Zwecke der Abwicklung des Bewerbungsverfahrens. Dies ist insbesondere dann der Fall, wenn ein Bewerber entsprechende Bewerbungsunterlagen auf dem elektronischen Wege, beispielsweise per E-Mail oder \u00fcber ein auf der Internetseite befindliches Kontaktformular, an uns \u00fcbermittelt. Rechtsgrundlage f\u00fcr die Verarbeitung ist Art. 6 Abs. 1 f DSGVO. Unser berechtigtes Interesse folgt aus dem Zweck der Vorbereitung, dem Abschluss und der Abwicklung von Franchise-Vertr\u00e4gen. Die Daten werden grunds\u00e4tzlich nach Ablauf der Verj\u00e4hrungsfrist gel\u00f6scht. Diese betr\u00e4gt derzeit 3 Jahre ab dem Schluss des Jahres, in dem ein etwaiges Vertragsverh\u00e4ltnis mit Ihnen beendet wird bzw. wenn kein Vertragsverh\u00e4ltnis mit Ihnen zustande kommt mit dem Schluss des Jahres, in dem Sie die Anfrage gestellt haben. Hiervon ausgenommen sind Daten, die aufgrund steuer- oder handelsrechtlicher Vorschriften von uns aufzubewahren sind. Die L\u00f6schung erfolgt dann nach Ablauf dieser Fristen, die derzeit zwischen 6 und 10 Jahren betragen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>g)&nbsp;&nbsp; &nbsp;Bei Nutzung unseres allgemeinen Kontaktformulars oder Kontaktaufnahme per E-Mail, Telefon oder Post<\/strong><br>Bei Fragen jeglicher Art bieten wir Ihnen die M\u00f6glichkeit, mit uns \u00fcber ein auf der Website bereitgestelltes Formular oder auf sonstige Weise (Telefon, E-Mail, Post) Kontakt aufzunehmen.<br>Bei der Nutzung des Kontakt-Formulars ist die Angabe des Namens, einer g\u00fcltigen E-Mail-Adresse und der Telefonnummer erforderlich, damit wir wissen, von wem die Anfrage stammt und um diese beantworten zu k\u00f6nnen bzw. Kontakt mit Ihnen aufnehmen zu k\u00f6nnen.<br>Bei der Kontaktaufnahme auf sonstige Weise erheben wir die zur Verf\u00fcgung gestellten Daten und ggfs. weitere Kontaktdaten, (Name, Vorname, ggf. Adresse, ggf. Telefonnummer, ggfs. E-Mail-Adresse) sowie den Inhalt Ihrer Anfrage, um Ihre Anfrage beantworten zu k\u00f6nnen.<br>Rechtsgrundlage f\u00fcr die Verarbeitung ist je nach Inhalt der Anfrage Art. 6 Abs. 1 lit b DSGVO bzw. Art. 6 Abs. 1 lit f. DSGVO. Unser berechtigtes Interesse folgt aus dem Zweck der Beantwortung Ihrer Anfrage. Bei Nutzung des Kontaktformulars erfolgt die Datenverarbeitung ferner nach Art. 6 Abs. 1 S. 1 lit. a DSGVO auf Grundlage Ihrer freiwillig erteilten Einwilligung.<br>Die erhobenen Daten werden in anonymisierter Form auch zu statistischen Zwecken verwendet. Rechtsgrundlage f\u00fcr diese Verarbeitung ist Art. 6 Abs. 1 S. 1 lit f DSGVO. Aus der Auswertung der Statistiken zur Optimierung unseres Angebots folgt das berechtigte Interesse.<br>Die Daten werden grunds\u00e4tzlich nach Ablauf der Verj\u00e4hrungsfrist gel\u00f6scht. Diese betr\u00e4gt derzeit 3 Jahre ab dem Schluss des Jahres, in dem ein etwaiges Vertragsverh\u00e4ltnis mit Ihnen beendet wird bzw. wenn kein Vertragsverh\u00e4ltnis mit Ihnen zustande kommt mit dem Schluss des Jahres, in dem Sie die Anfrage gestellt haben. Hiervon ausgenommen sind Daten, die aufgrund steuer- oder handelsrechtlicher Vorschriften von uns aufzubewahren sind. Die L\u00f6schung erfolgt dann nach Ablauf dieser Fristen, die derzeit zwischen 6 und 10 Jahren betragen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>h)&nbsp;&nbsp; &nbsp;Bei Nutzung des Kontaktformulars \u201ePresse\u201c<\/strong><br>Bei Presse-Anfragen bieten wir Ihnen die M\u00f6glichkeit, mit uns \u00fcber ein auf der Website bereitgestelltes Formular Kontakt aufzunehmen.<br>Bei der Nutzung des Kontakt-Formulars ist die Angabe des Namens, des Unternehmens, einer g\u00fcltigen E-Mail-Adresse und der Telefonnummer erforderlich, damit wir wissen, von wem die Anfrage stammt und um diese beantworten zu k\u00f6nnen bzw. Kontakt mit Ihnen aufnehmen zu k\u00f6nnen.<br>Rechtsgrundlage f\u00fcr die Verarbeitung ist je nach Inhalt der Anfrage Art. 6 Abs. 1 lit b DSGVO bzw. Art. 6 Abs. 1 lit f. DSGVO. Unser berechtigtes Interesse folgt aus dem Zweck der Beantwortung Ihrer Anfrage. Bei Nutzung des Kontaktformulars erfolgt die Datenverarbeitung ferner nach Art. 6 Abs. 1 S. 1 lit. a DSGVO auf Grundlage Ihrer freiwillig erteilten Einwilligung.<br>Die Daten werden grunds\u00e4tzlich nach Ablauf der Verj\u00e4hrungsfrist gel\u00f6scht. Diese betr\u00e4gt derzeit 3 Jahre ab dem Schluss des Jahres, in dem ein etwaiges Vertragsverh\u00e4ltnis mit Ihnen beendet wird bzw. wenn kein Vertragsverh\u00e4ltnis mit Ihnen zustande kommt mit dem Schluss des Jahres, in dem Sie die Anfrage gestellt haben. Hiervon ausgenommen sind Daten, die aufgrund steuer- oder handelsrechtlicher Vorschriften von uns aufzubewahren sind. Die L\u00f6schung erfolgt dann nach Ablauf dieser Fristen, die derzeit zwischen 6 und 10 Jahren betragen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>i)&nbsp;&nbsp; &nbsp;Daten von Mitarbeitern von Gesch\u00e4ftspartnern<\/strong><br>Wir speichern ggfs. die Kontaktdaten (Name, Vorname, Adresse, Telefonnummer, E-Mail-Adresse, Firmenzugeh\u00f6rigkeit) von Ansprechpartnern unserer Gesch\u00e4ftspartner zum Zweck der Vorbereitung, Abschluss und Abwicklung von Vertr\u00e4gen. Rechtsgrundlage f\u00fcr die Verarbeitung ist Art. 6 Abs. 1 lit. f DSGVO. Unser berechtigtes Interesse folgt aus dem Zweck der Vorbereitung, dem Abschluss und der Abwicklung von Vertr\u00e4gen. Die Daten werden grunds\u00e4tzlich nach Ablauf der Verj\u00e4hrungsfrist gel\u00f6scht. Diese betr\u00e4gt derzeit 3 Jahre ab dem Schluss des Jahres, in dem die Vertragsbeziehung mit dem Gesch\u00e4ftspartner beendet wird. Hiervon ausgenommen sind Daten, die aufgrund steuer- oder handelsrechtlicher Vorschriften von uns aufzubewahren sind. Die L\u00f6schung erfolgt dann nach Ablauf dieser Fristen, die derzeit zwischen 6 und 10 Jahren betragen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>j)&nbsp;&nbsp; &nbsp;Datenschutz bei Bewerbungen und im Bewerbungsverfahren<\/strong><br>Wir erheben und verarbeiten die personenbezogenen Daten von Bewerbern zum Zwecke der Abwicklung des Bewerbungsverfahrens. Rechtsgrundlage f\u00fcr die Verarbeitung ist Art. 88 DSGVO i. V. m. \u00a7 28 Bundesdatenschutzgesetz. Die Verarbeitung kann auch auf elektronischem Wege erfolgen. Dies ist insbesondere dann der Fall, wenn ein Bewerber entsprechende Bewerbungsunterlagen auf dem elektronischen Wege, beispielsweise per E-Mail oder \u00fcber ein auf der Internetseite befindliches Webformular, an uns \u00fcbermittelt. Schlie\u00dfen wir einen Vertrag mit einem Bewerber, werden die \u00fcbermittelten Daten zum Zwecke der Abwicklung des Vertragsverh\u00e4ltnisses unter Beachtung der gesetzlichen Vorschriften gespeichert. Wird von uns kein Vertrag mit dem Bewerber geschlossen, so werden die Bewerbungsunterlagen zwei Monate nach Abschluss des Bewerbungsverfahrens gel\u00f6scht, sofern einer L\u00f6schung keine sonstigen berechtigten Interessen unsererseits entgegenstehen. Sonstiges berechtigtes Interesse in diesem Sinne ist beispielsweise eine Beweispflicht in einem Verfahren nach dem Allgemeinen Gleichbehandlungsgesetz (AGG).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>k)&nbsp;&nbsp; &nbsp;Bei Nutzung eines unserer Kontaktformulare auf einer Yourfitstart Landing Page<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei Interesse an der Anforderung weiterer Informationen zu den (Start)Informationen der lokalen Franchisepartner bieten wir Ihnen die M\u00f6glichkeit, \u00fcber ein auf einer Landing Page bereitgestelltes Formular Kontakt aufzunehmen. Dabei ist die Angabe Ihres Namens, einer Telefonnummer, der E-Mail-Adresse notwendig, damit wir bzw. der lokale Franchisepartner Kontakt zu Ihnen aufnehmen und Ihnen weitere Informationen zur Verf\u00fcgung stellen k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Datenverarbeitung zum Zwecke der Kontaktaufnahme mit uns erfolgt nach Art. 6 Abs. 1 S. 1 lit. a DSGVO auf Grundlage Ihrer freiwillig erteilten Einwilligung. Rechtsgrundlage ist dar\u00fcber hinaus Art. 6 Abs, 1 S. 1 lit b DSGVO und Art. 6 Abs. 1 lit f DSGVO. Das berechtigte Interesse ergibt sich aus dem Interesse des Franchise-Partners Kunden im Zusammenhang mit einem Probetraining zu werben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die erhobenen Daten werden in anonymisierter Form auch zu statistischen Zwecken verwendet. Rechtsgrundlage f\u00fcr diese Verarbeitung ist Art. 6 Abs. 1 S. 1 lit f DSGVO. Aus der Auswertung der Statistiken zur Optimierung unseres Angebots folgt das berechtigte Interesse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir leiten diese Daten an den auf der Landing Page beworbenen lokalen Franchisepartner weiter, damit dieser mit Ihnen Kontakt wegen der (Start)Informationen aufnehmen kann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Weitergabe erfolgt nach Art. 6 Abs. 1 S. 1 lit. a DSGVO auf Grundlage Ihrer freiwillig erteilten Einwilligung. Rechtsgrundlage ist dar\u00fcber hinaus Art. 6 Abs, 1 S. 1 lit b DSGVO und Art. 6 Abs. 1 lit f DSGVO. Das berechtigte Interesse ergibt sich aus dem Interesse des Franchise-Partners Kunden im Zusammenhang mit den (Start)Informationen zu werben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die von uns erhobenen personenbezogenen Daten werden nach 6 Monaten gel\u00f6scht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Was macht YourFitStart.com mit den Daten?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">YourFitStart.com (mit Sitz in 1033 RX Amsterdam, Plotterstraat 22. KvK-Nummer: 70290458, USt-IDNr. NL858239231B01) agiert als Zwischenperson zwischen Verbrauchern und Unternehmen aus der Fitnessbranche. Die Kampagnen und Seiten auf dieser Website wurden von YourFitStart.com entwickelt und dienen dazu, Ihre Anfrage mit einem der angeschlossenen Partner in Kontakt zu bringen. Bei Fragen k\u00f6nnen Sie sich an die folgende E-Mail-Adresse wenden&nbsp;<a href=\"javascript:linkTo_UnCryptMailto('jxfiql7fkclXvlrocfqpqxoq+zlj');\">info(at)yourfitstart.com<\/a>.<br><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">3. Weitergabe von Daten<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Eine \u00dcbermittlung Ihrer personenbezogenen Daten an Dritte zu anderen als den im folgenden aufgef\u00fchrten Zwecken findet nicht statt.<br>Wir geben Ihre personenbezogenen Daten nur an Dritte weiter:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; wenn Sie Ihre nach Art. 6 Abs. 1 S. 1 lit. a DSGVO ausdr\u00fcckliche Einwilligung dazu erteilt haben,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; wenn die Weitergabe nach Art. 6 Abs. 1 S. 1 lit. f DSGVO zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen erforderlich ist und kein Grund zur Annahme besteht, dass Sie ein \u00fcberwiegendes schutzw\u00fcrdiges Interesse an der Nichtweitergabe Ihrer Daten haben,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; f\u00fcr den Fall, dass f\u00fcr die Weitergabe nach Art. 6 Abs. 1 S. 1 lit. c DSGVO eine gesetzliche Verpflichtung besteht, sowie<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; wenn dies gesetzlich zul\u00e4ssig und nach Art. 6 Abs. 1 S. 1 lit. b DSGVO f\u00fcr die Abwicklung von Vertragsverh\u00e4ltnissen mit Ihnen erforderlich ist oder nach Art. 6 Abs. 1 lit f DSGVO ein berechtigtes Interesse unsererseits besteht und und kein Grund zur Annahme besteht, dass Sie ein \u00fcberwiegendes schutzw\u00fcrdiges Interesse an der Nichtweitergabe der Daten haben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Die Weitergabe von Daten erfolgt insbesondere im Rahmen unserer Zusammenarbeit mit externen Dienstleistern, mit denen wir im Rahmen der Erbringung unserer Dienstleistungen zusammenarbeiten.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">4.&nbsp;&nbsp; &nbsp;Cookies<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Wir setzen auf unserer Seite Cookies ein. Hierbei handelt es sich um kleine Dateien, die Ihr Browser automatisch erstellt und die auf Ihrem Endger\u00e4t (Laptop, Tablet, Smartphone o.\u00e4.) gespeichert werden, wenn Sie unsere Seite besuchen.<br>In dem Cookie werden Informationen abgelegt, die sich jeweils im Zusammenhang mit dem spezifisch eingesetzten Endger\u00e4t ergeben. Dies bedeutet jedoch nicht, dass wir dadurch unmittelbar Kenntnis von Ihrer Identit\u00e4t erhalten.<br>Der Einsatz von Cookies dient einerseits dazu, die Nutzung unseres Angebots f\u00fcr Sie angenehmer zu gestalten. So setzen wir sogenannte Session-Cookies ein, um zu erkennen, dass Sie einzelne Seiten unserer Website bereits besucht haben. Diese werden nach Verlassen unserer Seite automatisch gel\u00f6scht.<br>Dar\u00fcber hinaus setzen wir ebenfalls zur Optimierung der Benutzerfreundlichkeit tempor\u00e4re Cookies ein, die f\u00fcr einen bestimmten festgelegten Zeitraum auf Ihrem Endger\u00e4t gespeichert werden. Besuchen Sie unsere Seite erneut, um unsere Dienste in Anspruch zu nehmen, wird automatisch erkannt, dass Sie bereits bei uns waren und welche Eingaben und Einstellungen sie get\u00e4tigt haben, um diese nicht noch einmal eingeben zu m\u00fcssen.<br>Zum anderen setzten wir Cookies ein, um die Nutzung unserer Website statistisch zu erfassen und zum Zwecke der Optimierung unseres Angebotes f\u00fcr Sie auszuwerten (siehe Ziff. 5). Diese Cookies erm\u00f6glichen es uns, bei einem erneuten Besuch unserer Seite automatisch zu erkennen, dass Sie bereits bei uns waren. Diese Cookies werden nach einer jeweils definierten Zeit automatisch gel\u00f6scht.<br>Die durch Cookies verarbeiteten Daten sind f\u00fcr die genannten Zwecke zur Wahrung unserer berechtigten Interessen sowie Dritter nach Art. 6 Abs. 1 S. 1 lit. f DSGVO erforderlich.<br>Die meisten Browser akzeptieren Cookies automatisch. Sie k\u00f6nnen Ihren Browser jedoch so konfigurieren, dass keine Cookies auf Ihrem Computer gespeichert werden oder stets ein Hinweis erscheint, bevor ein neuer Cookie angelegt wird. Die vollst\u00e4ndige Deaktivierung von Cookies kann jedoch dazu f\u00fchren, dass Sie nicht alle Funktionen unserer Website nutzen k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">5.&nbsp;&nbsp; &nbsp;Analyse Tools \/ Tracking Tools<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Die im Folgenden aufgef\u00fchrten und von uns eingesetzten Tracking-Ma\u00dfnahmen werden auf Grundlage des Art. 6 Abs. 1 S. 1 lit. f DSGVO durchgef\u00fchrt. Mit den zum Einsatz kommenden Tracking-Ma\u00dfnahmen wollen wir eine bedarfsgerechte Gestaltung und die fortlaufende Optimierung unserer Webseite sicherstellen. Zum anderen setzen wir die Tracking-Ma\u00dfnahmen ein, um die Nutzung unserer Webseite statistisch zu erfassen und zum Zwecke der Optimierung unseres Angebotes f\u00fcr Sie auszuwerten. Diese Interessen sind als berechtigt im Sinne der vorgenannten Vorschrift anzusehen.<br>Die jeweiligen Datenverarbeitungszwecke und Datenkategorien sind den entsprechenden Tracking-Tools zu entnehmen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>a)&nbsp;&nbsp; &nbsp;AT Internet<br><\/strong>F\u00fcr die Ermittlung der anonymen statistischen Kennwerte wird eine Technik der Firma AT Internet (<a href=\"https:\/\/www.atinternet.com\/de\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.atinternet.com\/de\/<\/a>) genutzt. Die durch diese Technik gesammelten Daten werden ausschlie\u00dflich anonymisiert auf Servern in Deutschland gespeichert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie haben in unseren Datenschutz-Einstellungen die M\u00f6glichkeit, der anonymen Erfassung Ihrer Nutzungsvorg\u00e4nge zu widersprechen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zur Weiterleitung der Daten an AT Internet wird der Google Tag Manager der Firma Google (<a href=\"https:\/\/about.google\/\">https:\/\/about.google\/<\/a>) verwendet. Dabei werden die Daten durch den Google Tag Manager nur weitergeleitet, jedoch nicht erhoben oder gespeichert. Der Tag Manager selbst setzt keine Cookies und verarbeitet keine Nutzer-Daten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>b)&nbsp;&nbsp; &nbsp;Google Adwords Conversion Tracking<\/strong><br>Um die Nutzung unserer Webseite statistisch zu erfassen und zum Zwecke der Optimierung unserer Website, nutzen wir ferner das Google Adwords Conversion Tracking. Dabei wird von Google Adwords ein Cookie (siehe Ziffer 4) auf Ihrem Rechner gesetzt, sofern Sie \u00fcber eine Google-Anzeige auf unsere Webseite gelangt sind.<br>Diese Cookies verlieren nach 30 Tagen ihre G\u00fcltigkeit und dienen nicht der pers\u00f6nlichen Identifizierung. Besucht der Nutzer bestimmte Seiten der Webseite des Adwords-Kunden und das Cookie ist noch nicht abgelaufen, k\u00f6nnen Google und der Kunde erkennen, dass der Nutzer auf die Anzeige geklickt hat und zu dieser Seite weitergeleitet wurde.<br>Jeder Adwords-Kunde erh\u00e4lt ein anderes Cookie. Cookies k\u00f6nnen somit nicht \u00fcber die Webseiten von Adwords-Kunden nachverfolgt werden. Die mithilfe des Conversion-Cookies eingeholten Informationen dienen dazu, Conversion-Statistiken f\u00fcr Adwords-Kunden zu erstellen, die sich f\u00fcr Conversion-Tracking entschieden haben. Die Adwords-Kunden erfahren die Gesamtanzahl der Nutzer, die auf ihre Anzeige geklickt haben und zu einer mit einem Conversion-Tracking-Tag versehenen Seite weitergeleitet wurden. Sie erhalten jedoch keine Informationen, mit denen sich Nutzer pers\u00f6nlich identifizieren lassen.<br>Wenn Sie nicht an dem Tracking-Verfahren teilnehmen m\u00f6chten, k\u00f6nnen Sie auch das hierf\u00fcr erforderliche Setzen eines Cookies ablehnen \u2013 etwa per Browser-Einstellung, die das automatische Setzen von Cookies generell deaktiviert. Sie k\u00f6nnen Cookies f\u00fcr Conversion-Tracking auch deaktivieren, indem Sie Ihren Browser so einstellen, dass Cookies von der Domain \u201ewww.googleadservices.com\u201c blockiert werden. Googles Datenschutzbelehrung zum Conversion-Tracking finden Sie hier (<a href=\"https:\/\/services.google.com\/sitestats\/de.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/services.google.com\/sitestats\/de.html<\/a>).<br><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">6.&nbsp;&nbsp; &nbsp;Social Media Plug-Ins<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Youtube<br><\/strong><br>Unsere Webseite nutzt Plug-Ins von YouTube, der YouTube, LLC, 901 Cherry Ave., San Bruno, CA 94066, USA, die eine Tochtergesellschaft der Google Inc., 1600 Amphitheatre Parkway, Mountain View, CA 94043-1351, USA ist.<br>Wenn Sie eine Seite unseres Webauftritts aufrufen, auf welcher ein YouTube-Video integriert wurde, wird eine direkte Verbindung zwischen Ihrem Browser und dem YouTube-Server hergestellt. YouTube und Google erhalten dadurch die Information, welche konkrete Unterseite mit Ihrer IP-Adresse besucht wurde.<br>Sofern Sie gleichzeitig bei YouTube eingeloggt ist, erkennt YouTube mit dem Aufruf einer Unterseite, die ein YouTube-Video enth\u00e4lt, welche konkrete Unterseite unserer Internetseite Sie besuchen. Diese Informationen werden durch YouTube und Google gesammelt und dem jeweiligen YouTube-Account zugeordnet.<br>YouTube und Google erhalten \u00fcber die YouTube-Komponente immer dann eine Information dar\u00fcber, dass Sie unsere Internetseite besucht haben, wenn Sie gleichzeitig bei YouTube eingeloggt sind, w\u00e4hrend Sie unsere Internetseite besuchen; dies findet unabh\u00e4ngig davon statt, ob Sie ein YouTube-Video anklicken oder nicht. Diese \u00dcbermittlung k\u00f6nnen Sie dadurch verhindern, dass sie sich vor einem Aufruf unserer Internetseite aus ihrem YouTube-Account ausloggen.<br>Die von YouTube ver\u00f6ffentlichten Datenschutzbestimmungen, die unter&nbsp;<a href=\"https:\/\/www.google.de\/intl\/de\/policies\/privacy\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.google.de\/intl\/de\/policies\/privacy\/<\/a>&nbsp;abrufbar sind, geben Aufschluss \u00fcber die Erhebung, Verarbeitung und Nutzung personenbezogener Daten durch YouTube und Google.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">7.&nbsp;&nbsp; &nbsp;Betroffenenrechte<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Sie haben das Recht:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; gem\u00e4\u00df Art. 7 Abs. 3 DSGVO Ihre einmal erteilte Einwilligung jederzeit gegen\u00fcber uns zu widerrufen. Dies hat zur Folge, dass wir die Datenverarbeitung, die auf dieser Einwilligung beruhte, f\u00fcr die Zukunft nicht mehr fortf\u00fchren d\u00fcrfen;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; gem\u00e4\u00df Art. 15 DSGVO Auskunft \u00fcber Ihre von uns verarbeiteten personenbezogenen Daten zu verlangen. Insbesondere k\u00f6nnen Sie Auskunft \u00fcber die Verarbeitungszwecke, die Kategorie der personenbezogenen Daten, die Kategorien von Empf\u00e4ngern, gegen\u00fcber denen Ihre Daten offengelegt wurden oder werden, die geplante Speicherdauer, das Bestehen eines Rechts auf Berichtigung, L\u00f6schung, Einschr\u00e4nkung der Verarbeitung oder Widerspruch, das Bestehen eines Beschwerderechts, die Herkunft ihrer Daten, sofern diese nicht bei uns erhoben wurden, sowie \u00fcber das Bestehen einer automatisierten Entscheidungsfindung einschlie\u00dflich Profiling und ggf. aussagekr\u00e4ftigen Informationen zu deren Einzelheiten verlangen;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; gem\u00e4\u00df Art. 16 DSGVO unverz\u00fcglich die Berichtigung unrichtiger oder Vervollst\u00e4ndigung Ihrer bei uns gespeicherten personenbezogenen Daten zu verlangen;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; gem\u00e4\u00df Art. 17 DSGVO die L\u00f6schung Ihrer bei uns gespeicherten personenbezogenen Daten zu verlangen, soweit nicht die Verarbeitung zur Aus\u00fcbung des Rechts auf freie Meinungs\u00e4u\u00dferung und Information, zur Erf\u00fcllung einer rechtlichen Verpflichtung, aus Gr\u00fcnden des \u00f6ffentlichen Interesses oder zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen erforderlich ist;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; gem\u00e4\u00df Art. 18 DSGVO die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen, soweit die Richtigkeit der Daten von Ihnen bestritten wird, die Verarbeitung unrechtm\u00e4\u00dfig ist, Sie aber deren L\u00f6schung ablehnen und wir die Daten nicht mehr ben\u00f6tigen, Sie jedoch diese zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen ben\u00f6tigen oder Sie gem\u00e4\u00df Art. 21 DSGVO Widerspruch gegen die Verarbeitung eingelegt haben;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; gem\u00e4\u00df Art. 20 DSGVO Ihre personenbezogenen Daten, die Sie uns bereitgestellt haben, in einem strukturierten, g\u00e4ngigen und maschinenlesebaren Format zu erhalten oder die \u00dcbermittlung an einen anderen Verantwortlichen zu verlangen; und<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; gem\u00e4\u00df Art. 77 DSGVO sich bei einer Aufsichtsbeh\u00f6rde zu beschweren. In der Regel k\u00f6nnen Sie sich hierf\u00fcr an die Aufsichtsbeh\u00f6rde Ihres \u00fcblichen Aufenthaltsortes oder Arbeitsplatzes oder unseres Sitzes wenden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">8.&nbsp;&nbsp; &nbsp;Widerspruchsrecht<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Sofern Ihre personenbezogenen Daten auf Grundlage von berechtigten Interessen gem\u00e4\u00df Art. 6 Abs. 1 S. 1 lit. f DSGVO verarbeitet werden, haben Sie das Recht, gem\u00e4\u00df Art. 21 DSGVO Widerspruch gegen die Verarbeitung Ihrer personenbezogenen Daten einzulegen, soweit daf\u00fcr Gr\u00fcnde vorliegen, die sich aus Ihrer besonderen Situation ergeben oder sich der Widerspruch gegen Direktwerbung richtet. Im letzteren Fall haben Sie ein generelles Widerspruchsrecht, das ohne Angabe einer besonderen Situation von uns umgesetzt wird.<br>M\u00f6chten Sie von Ihrem Widerrufs- oder Widerspruchsrecht Gebrauch machen, gen\u00fcgt eine E-Mail an&nbsp;<a href=\"mailto:info@mrssporty.de\">info@mrssporty.de<\/a><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">9.&nbsp;&nbsp; &nbsp;Datensicherheit<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Wir verwenden innerhalb des Website-Besuchs das verbreitete TLS-Verfahren (Transport Layer Security) in Verbindung mit der jeweils h\u00f6chsten Verschl\u00fcsselungsstufe, die von Ihrem Browser unterst\u00fctzt wird. In der Regel handelt es sich dabei um eine 256 Bit Verschl\u00fcsselung. Falls Ihr Browser keine 256-Bit Verschl\u00fcsselung unterst\u00fctzt, greifen wir stattdessen auf eine 128-Bit Verschl\u00fcsselung (mind. TLS1.0) zur\u00fcck. Als allerletzte M\u00f6glichkeit kann eine Verschl\u00fcsselung im DES-Format Modus CBC3 erfolgen. Dies ist eine 168 Bit, bestehend aus 3 x 56 Bit Schl\u00fcsseln. Diese Verschl\u00fcsselung ist sicher, f\u00fchrt aber ggf. zu l\u00e4ngeren Ladezeiten. Ob eine einzelne Seite unseres Internetauftrittes verschl\u00fcsselt \u00fcbertragen wird, erkennen Sie an der geschlossenen Darstellung des Sch\u00fcssel- beziehungsweise Schloss-Symbols in der unteren Statusleiste Ihres Browsers.<br>Wir bedienen uns im \u00dcbrigen geeigneter technischer und organisatorischer Sicherheitsma\u00dfnahmen, um Ihre Daten gegen zuf\u00e4llige oder vors\u00e4tzliche Manipulationen, teilweisen oder vollst\u00e4ndigen Verlust, Zerst\u00f6rung oder gegen den unbefugten Zugriff Dritter zu sch\u00fctzen. Unsere Sicherheitsma\u00dfnahmen werden entsprechend der technologischen Entwicklung fortlaufend verbessert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">10.&nbsp;&nbsp; &nbsp;Aktualit\u00e4t und \u00c4nderung der Datenschutzerkl\u00e4rung<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Datenschutzerkl\u00e4rung ist aktuell g\u00fcltig und hat den Stand Mai 2018.<br>Durch die Weiterentwicklung unserer Website und Angebote dar\u00fcber oder aufgrund ge\u00e4nderter gesetzlicher beziehungsweise beh\u00f6rdlicher Vorgaben kann es notwendig werden, diese Datenschutzerkl\u00e4rung zu \u00e4ndern. Die jeweils aktuelle Datenschutzerkl\u00e4rung kann jederzeit auf der Website unter&nbsp;<a href=\"https:\/\/www.mrssporty.de\/datenschutz\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.mrssporty.de\/datenschutz<\/a>&nbsp;von Ihnen abgerufen und ausgedruckt werden.<\/p>\n\n\n\n<p class=\"gs_A8o9Gh wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n<div  class=\"row_wrap has-background\"><div id='bg_6a57bafa63a2b' class='greyd-background bg_full'>\n\t\t\t\t\t\t\t\t<div class='bg_color'><\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n<div class=\"wp-block-columns row_xxxl has-color-63-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" id=\"Sp-M\">\n<div class=\"wp-block-column col-12 col-sm-auto is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%;width:100%\"><div  class=\"spacer_wrap \" aria-hidden=\"true\"><div class=\"wp-block-spacer inner-sm\" style=\"height:calc(152px * 0.4)\" aria-hidden=\"true\"><\/div><div class=\"wp-block-spacer inner-md\" style=\"height:calc(152px * 0.6)\" aria-hidden=\"true\"><\/div><div class=\"wp-block-spacer inner-lg\" style=\"height:calc(152px * 0.8)\" aria-hidden=\"true\"><\/div><div class=\"wp-block-spacer inner-xl\" style=\"height:152px\" aria-hidden=\"true\"><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n<div  id=\"Teaserboxen\" class=\"dynamic row_xxxl\"><div  class=\"row_wrap\">\n<div class=\"wp-block-columns row_xxl flex-stretch-content-sm is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column col-12 col-sm-auto dyn is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group gs_nOzonY group_wrap\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-greyd-box dyn gs_qNB0Bq greyd-content-box gs_qNB0Bq\"><figure style=\"\" class=\"wp-block-image greyd-image clrliladark shownone dyn  gs_o3LcLi\"><img decoding=\"async\" src=\"https:\/\/www.mrssporty.at\/club\/hollabrunn\/wp-content\/uploads\/sites\/89\/2023\/01\/icn_gruender.svg\" class=\"wp-image-428\" alt=\"icn_gruender\" \/><\/figure>\n\n\n<h2 class=\"dyn has-h-4-font-size wp-block-heading gs_s8T4Li\" style=\"font-style:normal;font-weight:700\">Steckt ein*e Gr\u00fcnder*in in dir?<\/h2>\n\n\n\n<p class=\"shownone dyn gs_FVC2UQ wp-block-paragraph\">Besser selbstst\u00e4ndig mit dem gr\u00f6\u00dften europ\u00e4ischen Franchise Frauen-Fitness Konzept.<\/p>\n\n\n\n<div class=\"wp-block-greyd-buttons alignleft\"><a  href=\"https:\/\/www.mrssporty-franchise.at\/\" class=\"button is-style-sec dyn gs_cMEEZW \">Gr\u00fcnde jetzt mit Mrs.Sporty<\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column col-12 col-sm-auto dyn is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-greyd-box dyn gs_qNB0Bq greyd-content-box gs_qNB0Bq\"><figure style=\"\" class=\"wp-block-image greyd-image clrliladark shownone dyn  gs_o3LcLi\"><img decoding=\"async\" src=\"https:\/\/www.mrssporty.at\/club\/hollabrunn\/wp-content\/uploads\/sites\/89\/2023\/01\/icn_karriere.svg\" class=\"wp-image-423\" alt=\"icn_karriere\" \/><\/figure>\n\n\n<h2 class=\"dyn has-h-4-font-size wp-block-heading gs_s8T4Li\" style=\"font-style:normal;font-weight:700\">Jobs bei Mrs.Sporty<br><\/h2>\n\n\n\n<p class=\"shownone dyn gs_FVC2UQ wp-block-paragraph\">Mrs.Sporty bringt Bewegung in Deine Karriere. In der Zentrale in Berlin oder in einem unserer Clubs.<\/p>\n\n\n\n<div class=\"wp-block-greyd-buttons alignleft\"><a  href=\"https:\/\/www.mrssporty.at\/karriere\/\" class=\"button is-style-sec dyn gs_cMEEZW \">Jobangebote ansehen<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Datenschutzerkl\u00e4rung Der Schutz personenbezogenen Daten sowie der Privatsph\u00e4re von Besuchern der Website&nbsp;www.mrssporty.de&nbsp;ist ein besonderes Anliegen der Mrs.Sporty GmbH, Helmholtzstra\u00dfe 2-9, 10587 Berlin. Aus diesem Grund setzen wir uns nach bestem Wissen und Gewissen f\u00fcr den Schutz Ihrer Privatsph\u00e4re und Ihr Recht auf Datenschutz ein, indem wir die ma\u00dfgeblichen datenschutzrechtlichen Vorschriften beachten. Die Erhebung, Speicherung und [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"greyd_block_editor_preview":[],"footnotes":""},"class_list":["post-1603","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datenschutz - Mrs.Sporty Club Hollabrunn<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mrssporty.at\/club\/hollabrunn\/datenschutz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutz - Mrs.Sporty Club Hollabrunn\" \/>\n<meta property=\"og:description\" content=\"Datenschutzerkl\u00e4rung Der Schutz personenbezogenen Daten sowie der Privatsph\u00e4re von Besuchern der Website&nbsp;www.mrssporty.de&nbsp;ist ein besonderes Anliegen der Mrs.Sporty GmbH, Helmholtzstra\u00dfe 2-9, 10587 Berlin. Aus diesem Grund setzen wir uns nach bestem Wissen und Gewissen f\u00fcr den Schutz Ihrer Privatsph\u00e4re und Ihr Recht auf Datenschutz ein, indem wir die ma\u00dfgeblichen datenschutzrechtlichen Vorschriften beachten. Die Erhebung, Speicherung und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mrssporty.at\/club\/hollabrunn\/datenschutz\/\" \/>\n<meta property=\"og:site_name\" content=\"Mrs.Sporty Club Hollabrunn\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-20T16:50:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mrssporty.at\\\/club\\\/hollabrunn\\\/datenschutz\\\/\",\"url\":\"https:\\\/\\\/www.mrssporty.at\\\/club\\\/hollabrunn\\\/datenschutz\\\/\",\"name\":\"Datenschutz - Mrs.Sporty Club Hollabrunn\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mrssporty.at\\\/club\\\/hollabrunn\\\/#website\"},\"datePublished\":\"2023-04-19T10:00:04+00:00\",\"dateModified\":\"2023-07-20T16:50:27+00:00\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mrssporty.at\\\/club\\\/hollabrunn\\\/datenschutz\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mrssporty.at\\\/club\\\/hollabrunn\\\/#website\",\"url\":\"https:\\\/\\\/www.mrssporty.at\\\/club\\\/hollabrunn\\\/\",\"name\":\"Mrs.Sporty Club Hollabrunn\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mrssporty.at\\\/club\\\/hollabrunn\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mrssporty.at\\\/club\\\/hollabrunn\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mrssporty.at\\\/club\\\/hollabrunn\\\/#organization\",\"name\":\"Mrs.Sporty Club Hollabrunn\",\"url\":\"https:\\\/\\\/www.mrssporty.at\\\/club\\\/hollabrunn\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.mrssporty.at\\\/club\\\/hollabrunn\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mrssporty.at\\\/club\\\/hollabrunn\\\/wp-content\\\/uploads\\\/sites\\\/89\\\/2023\\\/04\\\/Logo-Sporty.svg\",\"contentUrl\":\"https:\\\/\\\/www.mrssporty.at\\\/club\\\/hollabrunn\\\/wp-content\\\/uploads\\\/sites\\\/89\\\/2023\\\/04\\\/Logo-Sporty.svg\",\"caption\":\"Mrs.Sporty Club Hollabrunn\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mrssporty.at\\\/club\\\/hollabrunn\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutz - Mrs.Sporty Club Hollabrunn","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/datenschutz\/","og_locale":"de_DE","og_type":"article","og_title":"Datenschutz - Mrs.Sporty Club Hollabrunn","og_description":"Datenschutzerkl\u00e4rung Der Schutz personenbezogenen Daten sowie der Privatsph\u00e4re von Besuchern der Website&nbsp;www.mrssporty.de&nbsp;ist ein besonderes Anliegen der Mrs.Sporty GmbH, Helmholtzstra\u00dfe 2-9, 10587 Berlin. Aus diesem Grund setzen wir uns nach bestem Wissen und Gewissen f\u00fcr den Schutz Ihrer Privatsph\u00e4re und Ihr Recht auf Datenschutz ein, indem wir die ma\u00dfgeblichen datenschutzrechtlichen Vorschriften beachten. Die Erhebung, Speicherung und [&hellip;]","og_url":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/datenschutz\/","og_site_name":"Mrs.Sporty Club Hollabrunn","article_modified_time":"2023-07-20T16:50:27+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/datenschutz\/","url":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/datenschutz\/","name":"Datenschutz - Mrs.Sporty Club Hollabrunn","isPartOf":{"@id":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/#website"},"datePublished":"2023-04-19T10:00:04+00:00","dateModified":"2023-07-20T16:50:27+00:00","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mrssporty.at\/club\/hollabrunn\/datenschutz\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/#website","url":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/","name":"Mrs.Sporty Club Hollabrunn","description":"","publisher":{"@id":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/#organization","name":"Mrs.Sporty Club Hollabrunn","url":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/#\/schema\/logo\/image\/","url":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/wp-content\/uploads\/sites\/89\/2023\/04\/Logo-Sporty.svg","contentUrl":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/wp-content\/uploads\/sites\/89\/2023\/04\/Logo-Sporty.svg","caption":"Mrs.Sporty Club Hollabrunn"},"image":{"@id":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/wp-json\/wp\/v2\/pages\/1603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/wp-json\/wp\/v2\/comments?post=1603"}],"version-history":[{"count":18,"href":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/wp-json\/wp\/v2\/pages\/1603\/revisions"}],"predecessor-version":[{"id":3294,"href":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/wp-json\/wp\/v2\/pages\/1603\/revisions\/3294"}],"wp:attachment":[{"href":"https:\/\/www.mrssporty.at\/club\/hollabrunn\/wp-json\/wp\/v2\/media?parent=1603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}